{"id":5434,"date":"2017-08-11T15:36:20","date_gmt":"2017-08-11T15:36:20","guid":{"rendered":"http:\/\/estatebkk.com\/condos\/?p=5434"},"modified":"2017-10-06T15:35:09","modified_gmt":"2017-10-06T15:35:09","slug":"belle-grand-rama9-r1268","status":"publish","type":"post","link":"https:\/\/estatebkk.com\/condos\/belle-grand-rama9-r1268\/","title":{"rendered":"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station"},"content":{"rendered":"<div class=\"title\">\n<div class=\"row\">\n<h2 class=\"style1\">Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32)<\/h2>\n<\/div>\n<div class=\"row\">\n<p>| Rama 9 alley 3, Ratchadapisek Rd., Huai Khwang, Bangkok |<\/p>\n<\/div>\n<div class=\"row\">\n<p>98 sqm | 3 bedroom | 2 bathroom | 11th FL | 50000 THB\/month <\/p>\n<\/div>\n<div class=\"row\">\n<p>| close to lots of restaurants and shops |<\/p>\n<\/div>\n<div class=\"row\">\n<p>Property ID: R1268 <\/p>\n<\/div>\n<\/div>\n<div class=\"info-2\">\n<div class=\"row\">\n<div class=\"row-1\">\n<p>Room features:<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>air conditioners<\/p>\n<p>sofa<\/p>\n<p>bed sets<\/p>\n<p>dining table and chairs<\/p>\n<p>closet<\/p>\n<p>LCD TV <\/p>\n<p>fitted kitchen with refrigerator, microwave, electric stove\/cooker hood<\/p>\n<p>bathroom with walk-in shower + water heater<\/p>\n<p>washing machine<\/p>\n<p>balconies<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>Location:<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>Rama 9 alley 3, Ratchadapisek Rd., Huai Khwang, Bangkok<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>Project Info:<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>27-43 storey condominium buildings, 1992 units<\/p>\n<p>42-220 sqm. (1-3 bedroom)<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>Facility:<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>gym<\/p>\n<p>swimming pool<\/p>\n<p>garden<\/p>\n<p>kid\u2019s playground<\/p>\n<p>laundry facility<\/p>\n<p>on-site shops, supermarket, 7\/11 and restaurants<\/p>\n<p>shuttle service to MRT<\/p>\n<p>parking space<\/p>\n<p>24 hours security system<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>Nearby:<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>Rama 9 MRT subway station (400 m.)<\/p>\n<p>Thailand Cultural Center MRT subway station (1.4 km.)<\/p>\n<p>Central Plaza Rama 9 (300 m.)<\/p>\n<p>Fortune town building (700 m.)<\/p>\n<p>Tesco Lotus superstore (550 m.)<\/p>\n<p>The Nine tower (200 m.)<\/p>\n<p>Esplanade shopping mall (1.3 km.)<\/p>\n<p>Big C Extra supermarket (1.7 km.)<\/p>\n<p>The Street Ratchada shopping plaza (1.9 km.)<\/p>\n<p>True tower (950 m.)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"gallery\">\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">This slideshow requires JavaScript.<\/p><div id=\"gallery-5434-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/1-15.jpg&quot;,&quot;id&quot;:&quot;5268&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/2-14.jpg&quot;,&quot;id&quot;:&quot;5269&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/3-17.jpg&quot;,&quot;id&quot;:&quot;5270&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/8-9.jpg&quot;,&quot;id&quot;:&quot;5275&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/7-12.jpg&quot;,&quot;id&quot;:&quot;5274&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/6-13.jpg&quot;,&quot;id&quot;:&quot;5273&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/5-12.jpg&quot;,&quot;id&quot;:&quot;5272&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/4-16.jpg&quot;,&quot;id&quot;:&quot;5271&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/9-7.jpg&quot;,&quot;id&quot;:&quot;5276&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/3-1.jpeg&quot;,&quot;id&quot;:&quot;5277&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/2-1.jpeg&quot;,&quot;id&quot;:&quot;5278&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/5-1.jpeg&quot;,&quot;id&quot;:&quot;5279&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/estatebkk.com\\\/condos\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/7-1.jpeg&quot;,&quot;id&quot;:&quot;5280&quot;,&quot;title&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;alt&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;caption&quot;:&quot;Belle Grand Rama 9 (\\u0e41\\u0e1a\\u0e25 \\u0e41\\u0e01\\u0e23\\u0e19\\u0e14\\u0e4c \\u0e1e\\u0e23\\u0e30\\u0e23\\u0e32\\u0e21 9)&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div><\/p>\n<\/div>\n<div class=\"info-3\">\n<div class=\"row\">\n<div class=\"row-1\">\n<p>\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e41\u0e02\u0e27\u0e07\u0e2b\u0e49\u0e27\u0e22\u0e02\u0e27\u0e32\u0e07 \u0e40\u0e02\u0e15\u0e2b\u0e49\u0e27\u0e22\u0e02\u0e27\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 27-43 \u0e0a\u0e31\u0e49\u0e19, 1992 \u0e22\u0e39\u0e19\u0e34\u0e15<\/p>\n<p>42-220 \u0e15\u0e23\u0e21. 1-3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a<\/p>\n<p>\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33<\/p>\n<p>\u0e2a\u0e27\u0e19<\/p>\n<p>\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19<\/p>\n<p>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d<\/p>\n<p>\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23<\/p>\n<p>\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07<\/p>\n<p>\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16<\/p>\n<p>\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"row-1\">\n<p>\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e01\u0e25\u0e49\u0e40\u0e04\u0e35\u0e22\u0e07<\/p>\n<\/div>\n<div class=\"row-2\">\n<p>\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 (400 \u0e21.)<\/p>\n<p>\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (1.4 \u0e01\u0e21.)<\/p>\n<p>\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 (300 \u0e21.)<\/p>\n<p>\u0e15\u0e36\u0e01\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c (700 \u0e21.)<\/p>\n<p>\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e19\u0e19\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c (200 \u0e21.)<\/p>\n<p>\u0e40\u0e17\u0e2a\u0e42\u0e01\u0e49\u0e42\u0e25\u0e15\u0e31\u0e2a (550 \u0e21.)<\/p>\n<p>\u0e40\u0e2d\u0e2a\u0e1e\u0e25\u0e32\u0e19\u0e32\u0e14 (1.3 \u0e01\u0e21.)<\/p>\n<p>\u0e1a\u0e34\u0e4a\u0e01\u0e0b\u0e35\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c (1.7 \u0e01\u0e21.)<\/p>\n<p>\u0e40\u0e14\u0e2d\u0e30\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e23\u0e31\u0e0a\u0e14\u0e32 (1.9 \u0e01\u0e21.)<\/p>\n<p>\u0e17\u0e23\u0e39\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c (950 \u0e21.)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wrap2\"><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3875.311708149288!2d100.56723531483057!3d13.760066690342079!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x30e29e8b89948df9%3A0xb209ddbd1f7910d0!2sBelle+Condominium!5e0!3m2!1sen!2s!4v1502300778318\" width=\"100%\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe>\n<\/div>\n<div class=\"wrap3\"><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m0!4v1502300895952!6m8!1m7!1sp7X4vwhEoZvatkriose5dw!2m2!1d13.75957285792284!2d100.5681232234684!3f54.06609518113152!4f5.223117886304237!5f0.7820865974627469\" width=\"100%\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/div>\n<div class=\"wrap3\">\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/samyan-mrt\/\" target=\"_blank\"><br \/>\n1 &#8211; condos for rent near Hua Lamphong MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/samyan-mrt\/\" target=\"_blank\"><br \/>\n2 &#8211; condos for rent near Samyan MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/saladaeng-bts\/\" target=\"_blank\"><br \/>\n3 &#8211; condos for rent near Saladaeng BTS\/Silom MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/lumphini-mrt\/\" target=\"_blank\"><br \/>\n4 &#8211; condos for rent near Lumphini MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/khlong-toei-mrt\/\" target=\"_blank\"><br \/>\n5 &#8211; condos for rent near Khlong Toei MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/queen-sirikit-national-convention-centre-mrt\/\" target=\"_blank\"><br \/>\n6 &#8211; condos for rent near Queen Sirikit National Convention Centre MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/asoke-bts\/\" target=\"_blank\"><br \/>\n7 &#8211; condos for rent near Asoke BTS\/ Sukhumvit MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/phetchaburi-mrt\/\" target=\"_blank\"><br \/>\n8 &#8211; condos for rent near Phetchaburi MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/\" target=\"_blank\"><br \/>\n9 &#8211; condos for rent near Phra Ram 9 MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/thailand-cultural-centre-mrt\/\" target=\"_blank\"><br \/>\n10 &#8211; condos for rent near Thailand Cultural Centre MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/huaikhwang-mrt\/\" target=\"_blank\"><br \/>\n11 &#8211; condos for rent near Huai Khwang MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/sutthisan-mrt\/\" target=\"_blank\"><br \/>\n12 &#8211; condos for rent near Sutthisan MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/ratchadaphisek-mrt\/\" target=\"_blank\"><br \/>\n13 &#8211; condos for rent near Ratchadaphisek MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/latphrao-ladprao-mrt\/\" target=\"_blank\"><br \/>\n14 &#8211; condos for rent near Lat Phrao MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/phahonyothin-mrt\/\" target=\"_blank\"><br \/>\n15 &#8211; condos for rent near Phahon Yothin MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/mochit-bts\/\" target=\"_blank\"><br \/>\n16 &#8211; condos for rent near Chatuchak Park MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/mochit-bts\/\" target=\"_blank\"><br \/>\n17 &#8211; condos for rent near Kamphaeng Phet MRT, Bangkok<\/a><\/p>\n<p><a class=\"style83\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/bangsue-mrt\/\" target=\"_blank\"><br \/>\n18 &#8211; condos for rent near Bang Sue MRT, Bangkok<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32) | Rama 9 alley 3, Ratchadapisek Rd., Huai Khwang, Bangkok | 98 sqm | 3 bedroom | 2 bathroom | 11th FL | 50000 THB\/month | close to lots of restaurants&hellip; <br \/><a class=\"read-more-button\" href=\"https:\/\/estatebkk.com\/condos\/belle-grand-rama9-r1268\/\" target=\"_blank\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":5268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[313,98,82,300,312,376,296],"tags":[314],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station\" \/>\n<meta property=\"og:description\" content=\"Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32) | Rama 9 alley 3, Ratchadapisek Rd., Huai Khwang, Bangkok | 98 sqm | 3 bedroom | 2 bathroom | 11th FL | 50000 THB\/month | close to lots of restaurants&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/\" \/>\n<meta property=\"og:site_name\" content=\"Condos &amp; Apartments for rent in Bangkok\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-11T15:36:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-06T15:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"condos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"condos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/estatebkk.com\/condos\/belle-grand-rama9-r1268\/\",\"url\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/\",\"name\":\"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station\",\"isPartOf\":{\"@id\":\"https:\/\/estatebkk.com\/condos\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg\",\"datePublished\":\"2017-08-11T15:36:20+00:00\",\"dateModified\":\"2017-10-06T15:35:09+00:00\",\"author\":{\"@id\":\"https:\/\/estatebkk.com\/condos\/#\/schema\/person\/e709d2a83a39f7fef0897bc681d27d58\"},\"breadcrumb\":{\"@id\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage\",\"url\":\"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg\",\"contentUrl\":\"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg\",\"width\":600,\"height\":450,\"caption\":\"Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/estatebkk.com\/condos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/estatebkk.com\/condos\/#website\",\"url\":\"https:\/\/estatebkk.com\/condos\/\",\"name\":\"Condos &amp; Apartments for rent in Bangkok\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/estatebkk.com\/condos\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/estatebkk.com\/condos\/#\/schema\/person\/e709d2a83a39f7fef0897bc681d27d58\",\"name\":\"condos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/","og_locale":"en_US","og_type":"article","og_title":"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station","og_description":"Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32) | Rama 9 alley 3, Ratchadapisek Rd., Huai Khwang, Bangkok | 98 sqm | 3 bedroom | 2 bathroom | 11th FL | 50000 THB\/month | close to lots of restaurants&hellip; Read more","og_url":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/","og_site_name":"Condos &amp; Apartments for rent in Bangkok","article_published_time":"2017-08-11T15:36:20+00:00","article_modified_time":"2017-10-06T15:35:09+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg","type":"image\/jpeg"}],"author":"condos","twitter_card":"summary_large_image","twitter_misc":{"Written by":"condos","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/estatebkk.com\/condos\/belle-grand-rama9-r1268\/","url":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/","name":"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station","isPartOf":{"@id":"https:\/\/estatebkk.com\/condos\/#website"},"primaryImageOfPage":{"@id":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage"},"image":{"@id":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage"},"thumbnailUrl":"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg","datePublished":"2017-08-11T15:36:20+00:00","dateModified":"2017-10-06T15:35:09+00:00","author":{"@id":"https:\/\/estatebkk.com\/condos\/#\/schema\/person\/e709d2a83a39f7fef0897bc681d27d58"},"breadcrumb":{"@id":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#primaryimage","url":"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg","contentUrl":"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg","width":600,"height":450,"caption":"Belle Grand Rama 9 (\u0e41\u0e1a\u0e25 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9)"},{"@type":"BreadcrumbList","@id":"http:\/\/estatebkk.com\/condos\/rent\/area\/rama9-mrt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/estatebkk.com\/condos\/"},{"@type":"ListItem","position":2,"name":"Belle Grand Rama 9 | condo for rent in Ratchada, Bangkok | 5 mins walk to Phra Ram 9 MRT subway station"}]},{"@type":"WebSite","@id":"https:\/\/estatebkk.com\/condos\/#website","url":"https:\/\/estatebkk.com\/condos\/","name":"Condos &amp; Apartments for rent in Bangkok","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estatebkk.com\/condos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/estatebkk.com\/condos\/#\/schema\/person\/e709d2a83a39f7fef0897bc681d27d58","name":"condos"}]}},"jetpack_featured_media_url":"https:\/\/estatebkk.com\/condos\/wp-content\/uploads\/2017\/08\/1-15.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8gv8H-1pE","_links":{"self":[{"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/posts\/5434"}],"collection":[{"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/comments?post=5434"}],"version-history":[{"count":0,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/posts\/5434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/media\/5268"}],"wp:attachment":[{"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/media?parent=5434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/categories?post=5434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estatebkk.com\/condos\/wp-json\/wp\/v2\/tags?post=5434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}